{"id":2014,"date":"2026-04-30T14:31:11","date_gmt":"2026-04-30T12:31:11","guid":{"rendered":"https:\/\/chicoshop.eu\/uncategorized\/blizzard-2\/"},"modified":"2026-07-10T15:09:07","modified_gmt":"2026-07-10T13:09:07","slug":"blizzard","status":"publish","type":"product","link":"https:\/\/chicoshop.eu\/de\/raketen\/blizzard\/","title":{"rendered":"Blizzard"},"content":{"rendered":"<p><strong>Blizzard<\/strong><br \/>\nBlizzard von Weco Feuerwerk ist ein Super Familien-Sortiment mit Raketen mit rubinroten Leuchtsternen und Brokat-Buketts; teilweise mit fetzigem Knall-Effekt. Dazu viele weitere tolle Leucht-, Sound-, Knall- und Jugendfeuerwerk-Highlights.<br \/>\n&nbsp;<\/p>\n<table border=\"0\" cellpadding=\"1\" cellspacing=\"1\">\n<tbody>\n<tr>\n<td>Artikelnummer:&nbsp;&nbsp;<\/td>\n<td>296111<\/td>\n<\/tr>\n<tr>\n<td>Bruttogewicht:<\/td>\n<td>0,45 kg<\/td>\n<\/tr>\n<tr>\n<td>EAN:<\/td>\n<td>4047291025936<\/td>\n<\/tr>\n<tr>\n<td>Einzelteile:<\/td>\n<td>95<\/td>\n<\/tr>\n<tr>\n<td>Kategorie:<\/td>\n<td>F2<\/td>\n<\/tr>\n<tr>\n<td>NEM:<\/td>\n<td>94,57 kg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Blizzard von Weco: Familien-Sortiment mit Raketen, roten Sternen, Brokat-Buketts, Knalleffekten und vielen Leucht- und Sound-Highlights. Bei Chicoshop<\/p>\n","protected":false},"featured_media":1118,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"pwb-brand":[62],"product_brand":[],"product_cat":[776],"product_tag":[],"class_list":["post-2014","product","type-product","status-publish","has-post-thumbnail","pwb-brand-weco-feuerwerk","product_cat-raketen","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"dsm_author":{"name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/638fe7b5aea5220dfb2b3f8c020592b51423e64d17738bb7b5f18efbb95352bf?s=96&d=mm&r=g","archive_link":"https:\/\/chicoshop.eu\/de\/author\/admin\/","biodata":""},"dsm_categories":[],"dsm_attachment_categories":[],"dsm_featured_image":{"thumbnail":"https:\/\/chicoshop.eu\/wp-content\/uploads\/2026\/04\/296111-weco-296111-blizzard-scaled-150x150.jpg","medium":"https:\/\/chicoshop.eu\/wp-content\/uploads\/2026\/04\/296111-weco-296111-blizzard-scaled-87x300.jpg","medium_large":"https:\/\/chicoshop.eu\/wp-content\/uploads\/2026\/04\/296111-weco-296111-blizzard-scaled-768x2643.jpg","large":"https:\/\/chicoshop.eu\/wp-content\/uploads\/2026\/04\/296111-weco-296111-blizzard-scaled-298x1024.jpg","1536x1536":"https:\/\/chicoshop.eu\/wp-content\/uploads\/2026\/04\/296111-weco-296111-blizzard-scaled-446x1536.jpg","2048x2048":"https:\/\/chicoshop.eu\/wp-content\/uploads\/2026\/04\/296111-weco-296111-blizzard-scaled-595x2048.jpg","et-pb-post-main-image":"https:\/\/chicoshop.eu\/wp-content\/uploads\/2026\/04\/296111-weco-296111-blizzard-scaled-400x250.jpg","et-pb-post-main-image-fullwidth":"https:\/\/chicoshop.eu\/wp-content\/uploads\/2026\/04\/296111-weco-296111-blizzard-scaled-837x675.jpg","et-pb-portfolio-image":"https:\/\/chicoshop.eu\/wp-content\/uploads\/2026\/04\/296111-weco-296111-blizzard-scaled-400x284.jpg","et-pb-portfolio-module-image":"https:\/\/chicoshop.eu\/wp-content\/uploads\/2026\/04\/296111-weco-296111-blizzard-scaled-510x382.jpg","et-pb-portfolio-image-single":"https:\/\/chicoshop.eu\/wp-content\/uploads\/2026\/04\/296111-weco-296111-blizzard-scaled.jpg","et-pb-gallery-module-image-portrait":"https:\/\/chicoshop.eu\/wp-content\/uploads\/2026\/04\/296111-weco-296111-blizzard-scaled-400x516.jpg","et-pb-post-main-image-fullwidth-large":"https:\/\/chicoshop.eu\/wp-content\/uploads\/2026\/04\/296111-weco-296111-blizzard-scaled-837x1800.jpg","et-pb-image--responsive--desktop":"https:\/\/chicoshop.eu\/wp-content\/uploads\/2026\/04\/296111-weco-296111-blizzard-scaled.jpg","et-pb-image--responsive--tablet":"https:\/\/chicoshop.eu\/wp-content\/uploads\/2026\/04\/296111-weco-296111-blizzard-scaled.jpg","et-pb-image--responsive--phone":"https:\/\/chicoshop.eu\/wp-content\/uploads\/2026\/04\/296111-weco-296111-blizzard-scaled-480x1652.jpg","gform-image-choice-sm":"https:\/\/chicoshop.eu\/wp-content\/uploads\/2026\/04\/296111-weco-296111-blizzard-scaled.jpg","gform-image-choice-md":"https:\/\/chicoshop.eu\/wp-content\/uploads\/2026\/04\/296111-weco-296111-blizzard-scaled.jpg","gform-image-choice-lg":"https:\/\/chicoshop.eu\/wp-content\/uploads\/2026\/04\/296111-weco-296111-blizzard-scaled.jpg","woocommerce_thumbnail":"https:\/\/chicoshop.eu\/wp-content\/uploads\/2026\/04\/296111-weco-296111-blizzard-scaled-300x300.jpg","woocommerce_single":"https:\/\/chicoshop.eu\/wp-content\/uploads\/2026\/04\/296111-weco-296111-blizzard-scaled-600x2065.jpg","woocommerce_gallery_thumbnail":"https:\/\/chicoshop.eu\/wp-content\/uploads\/2026\/04\/296111-weco-296111-blizzard-scaled-100x100.jpg","dgwt-wcas-product-suggestion":"https:\/\/chicoshop.eu\/wp-content\/uploads\/2026\/04\/296111-weco-296111-blizzard-scaled-64x220.jpg","full":"https:\/\/chicoshop.eu\/wp-content\/uploads\/2026\/04\/296111-weco-296111-blizzard-scaled.jpg"},"dsm_comment_count":0,"brands":[{"id":62,"name":"Weco Feuerwerk","slug":"weco-feuerwerk"}],"_links":{"self":[{"href":"https:\/\/chicoshop.eu\/de\/wp-json\/wp\/v2\/product\/2014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chicoshop.eu\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/chicoshop.eu\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/chicoshop.eu\/de\/wp-json\/wp\/v2\/comments?post=2014"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chicoshop.eu\/de\/wp-json\/wp\/v2\/media\/1118"}],"wp:attachment":[{"href":"https:\/\/chicoshop.eu\/de\/wp-json\/wp\/v2\/media?parent=2014"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/chicoshop.eu\/de\/wp-json\/wp\/v2\/pwb-brand?post=2014"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/chicoshop.eu\/de\/wp-json\/wp\/v2\/product_brand?post=2014"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/chicoshop.eu\/de\/wp-json\/wp\/v2\/product_cat?post=2014"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/chicoshop.eu\/de\/wp-json\/wp\/v2\/product_tag?post=2014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}